{"id":7879,"date":"2025-12-17T15:41:01","date_gmt":"2025-12-17T14:41:01","guid":{"rendered":"https:\/\/cpasixelles.brussels\/?page_id=7879"},"modified":"2025-12-17T16:05:35","modified_gmt":"2025-12-17T15:05:35","slug":"overzicht","status":"publish","type":"page","link":"https:\/\/cpasixelles.brussels\/nl\/het-ocmw\/sociale-coordinatie\/overzicht\/","title":{"rendered":"Overzicht"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;header-intern seniors&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;50px||50px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_4,3_4&#8243; module_class=&#8221;flex-zone&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2023\/05\/parlophone.png&#8221; alt=&#8221;CPAS Ixelles &#8211; Projet Dentelles&#8221; title_text=&#8221;parlophone&#8221; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;5%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;5%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Social co\u00f6rdinatie<\/h2>\n<h1>Overzicht<\/h1>\n<p>&nbsp;<br \/>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;80px||118px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|700||on|||||&#8221; header_2_text_color=&#8221;gcid-7d3e670f-2994-4496-b95f-1f022124e031&#8243; global_colors_info=&#8221;{%22gcid-7d3e670f-2994-4496-b95f-1f022124e031%22:%91%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>Overzicht van de leden van de Sociale Co\u00f6rdinatie<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]Ce r\u00e9pertoire contient les liens vers les sites des membres de la Coordination Sociale d\u2019Ixelles, r\u00e9partis en 11 secteurs d&#8217;activit\u00e9, tels que : Aide sociale, Logement, Emploi, Sant\u00e9, Information, Personnes \u00e2g\u00e9es, Jeunesse, Interculturel, Surendettement, Vie de quartier et Culture.<br \/>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Aide sociale<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2022\/01\/remi-walle-UOwvwZ9Dy6w-unsplash-1_ccexpress.jpeg&#8221; title_text=&#8221;mission&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/aide-sociale\/&#8221; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|130px|130px|130px|130px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Logement et Energie<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2022\/01\/Webp.net-resizeimage-6.jpg&#8221; title_text=&#8221;Webp.net-resizeimage (6)&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/logement-et-energie\/&#8221; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|130px|130px|130px|130px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Emploi et formation<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2022\/01\/CPAS_emploi_450_450.jpg&#8221; title_text=&#8221;CPAS_emploi_450_450&#8243; url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/emploi\/&#8221; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|130px|130px|130px|130px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/sante-et-sante-mentale\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Sant\u00e9 et Sant\u00e9 mentale<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2022\/01\/mariano-baraldi-IIBRFPj5LQk-unsplash-2-scaled.jpeg&#8221; title_text=&#8221;mariano-baraldi-IIBRFPj5LQk-unsplash 2&#8243; url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/sante-et-sante-mentale\/&#8221; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|130px|130px|130px|130px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/information-et-prevention\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Information et Pr\u00e9vention<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2022\/02\/cowomen-3ALW9V3jNkc-unsplash_ccexpress.jpeg&#8221; title_text=&#8221;cowomen-3ALW9V3jNkc-unsplash_ccexpress&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/information-et-prevention\/&#8221; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|130px|130px|130px|130px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/personnes-agees\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Personnes \u00e2g\u00e9es<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2022\/02\/jana-sabeth-snDUMdYF7o8-unsplash_ccexpress.jpeg&#8221; title_text=&#8221;Famille est personnes \u00e2g\u00e9es&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/personnes-agees\/&#8221; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|131px|131px|131px|131px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/jeunesse-et-petite-enfance-scolaire\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Jeunesse et Petite enfance<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2022\/01\/becca-tapert-GnY_mW1Q6Xc-unsplash_ccexpress.jpeg&#8221; alt=&#8221;woman in black shirt sitting on chair&#8221; title_text=&#8221;publications&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/jeunesse-et-petite-enfance-scolaire\/&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|155px|155px|155px|155px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/interculturel\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Interculturel<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2022\/01\/linkedin-sales-solutions-jJFrkJP_-RA-unsplash_ccexpress.jpeg&#8221; alt=&#8221;home aide etudiant&#8221; title_text=&#8221;linkedin-sales-solutions-jJFrkJP_-RA-unsplash_ccexpress&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/interculturel\/&#8221; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|130px|130px|130px|130px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||60px|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/surendettement\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Surendettement<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2022\/01\/Webp.net-resizeimage-14.jpg&#8221; title_text=&#8221;Webp.net-resizeimage (14)&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/surendettement\/&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|130px|130px|130px|130px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/vie-de-quartier\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Vie de quartier<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2021\/12\/placeholder-header-home-005.jpg&#8221; title_text=&#8221;icone-senior&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/vie-de-quartier\/&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|130px|130px|130px|130px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/culture\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Culture<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2022\/01\/Webp.net-resizeimage-8-1.jpg&#8221; title_text=&#8221;Webp.net-resizeimage (8) (1)&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/culture\/&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|130px|130px|130px|130px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Social steun<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2024\/10\/Aide_sociale.png&#8221; title_text=&#8221;Aide_sociale&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/nl\/sociale-steun\/&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Huisvesting en Energie<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2024\/10\/logement_energie.png&#8221; title_text=&#8221;logement_energie&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/nl\/huisvesting-en-energie\/&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Werkgelegenheid en opleiding<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2024\/10\/emplois_formation.png&#8221; title_text=&#8221;emplois_formation&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/nl\/werkgelegenheid-en-opleiding\/&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/sante-et-sante-mentale\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Gezondheid en geestelijke gezondheid<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2024\/10\/SANTE_SANTE-MENTAL.png&#8221; title_text=&#8221;SANTE_SANTE MENTAL&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/nl\/gezondheid-en-geestelijke-gezondheid\/&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/information-et-prevention\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Informatie en Preventie<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2024\/10\/INFO_Prevention.png&#8221; title_text=&#8221;INFO_Pr\u00e9vention&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/nl\/informatie-en-preventie\/&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/personnes-agees\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Ouderen<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2024\/10\/Personne_agee.png&#8221; title_text=&#8221;Personne_ag\u00e9e&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/nl\/ouderen\/&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/jeunesse-et-petite-enfance-scolaire\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Jongeren en jonge kinderen<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2024\/10\/jeunesse_petite-enfance.png&#8221; alt=&#8221;woman in black shirt sitting on chair&#8221; title_text=&#8221;jeunesse_petite enfance&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/nl\/jongeren-en-jonge-kinderen\/&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/interculturel\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Intercultureel<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2024\/10\/Interculturel.png&#8221; alt=&#8221;home aide etudiant&#8221; title_text=&#8221;Interculturel&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/nl\/intercultureel\/&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||60px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/surendettement\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Overmatige schuldenlast<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2024\/10\/surendettement.png&#8221; title_text=&#8221;surendettement&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/nl\/overmatige-schuldenlast\/&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/vie-de-quartier\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Buurtleven<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2024\/10\/Vie_quartier-2.png&#8221; title_text=&#8221;Vie_quartier&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/nl\/buurtleven\/&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/cpasixelles.brussels\/le-cpas\/coordination-sociale\/le-repertoire\/culture\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Cultuur<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2024\/10\/Culture.png&#8221; title_text=&#8221;Culture&#8221; url=&#8221;https:\/\/cpasixelles.brussels\/nl\/cultuur\/&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Social co\u00f6rdinatie Overzicht &nbsp; Overzicht van de leden van de Sociale Co\u00f6rdinatie Ce r\u00e9pertoire contient les liens vers les sites des membres de la Coordination Sociale d\u2019Ixelles, r\u00e9partis en 11 secteurs d&#8217;activit\u00e9, tels que : Aide sociale, Logement, Emploi, Sant\u00e9, Information, Personnes \u00e2g\u00e9es, Jeunesse, Interculturel, Surendettement, Vie de quartier et Culture. Aide sociale Logement et [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":6975,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-7879","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Overzicht - CPAS d&#039;Ixelles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cpasixelles.brussels\/nl\/overzicht\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Overzicht - CPAS d&#039;Ixelles\" \/>\n<meta property=\"og:description\" content=\"Social co\u00f6rdinatie Overzicht &nbsp; Overzicht van de leden van de Sociale Co\u00f6rdinatie Ce r\u00e9pertoire contient les liens vers les sites des membres de la Coordination Sociale d\u2019Ixelles, r\u00e9partis en 11 secteurs d&#039;activit\u00e9, tels que : Aide sociale, Logement, Emploi, Sant\u00e9, Information, Personnes \u00e2g\u00e9es, Jeunesse, Interculturel, Surendettement, Vie de quartier et Culture. Aide sociale Logement et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpasixelles.brussels\/nl\/overzicht\/\" \/>\n<meta property=\"og:site_name\" content=\"CPAS d&#039;Ixelles\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T15:05:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2022\/02\/MicrosoftTeams-image-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpasixelles.brussels\\\/nl\\\/overzicht\\\/\",\"url\":\"https:\\\/\\\/cpasixelles.brussels\\\/nl\\\/overzicht\\\/\",\"name\":\"Overzicht - CPAS d&#039;Ixelles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpasixelles.brussels\\\/#website\"},\"datePublished\":\"2025-12-17T14:41:01+00:00\",\"dateModified\":\"2025-12-17T15:05:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpasixelles.brussels\\\/nl\\\/overzicht\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpasixelles.brussels\\\/nl\\\/overzicht\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpasixelles.brussels\\\/nl\\\/overzicht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cpasixelles.brussels\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Overzicht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpasixelles.brussels\\\/#website\",\"url\":\"https:\\\/\\\/cpasixelles.brussels\\\/\",\"name\":\"CPAS d&#039;Ixelles\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpasixelles.brussels\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Overzicht - CPAS d&#039;Ixelles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cpasixelles.brussels\/nl\/overzicht\/","og_locale":"nl_NL","og_type":"article","og_title":"Overzicht - CPAS d&#039;Ixelles","og_description":"Social co\u00f6rdinatie Overzicht &nbsp; Overzicht van de leden van de Sociale Co\u00f6rdinatie Ce r\u00e9pertoire contient les liens vers les sites des membres de la Coordination Sociale d\u2019Ixelles, r\u00e9partis en 11 secteurs d'activit\u00e9, tels que : Aide sociale, Logement, Emploi, Sant\u00e9, Information, Personnes \u00e2g\u00e9es, Jeunesse, Interculturel, Surendettement, Vie de quartier et Culture. Aide sociale Logement et [&hellip;]","og_url":"https:\/\/cpasixelles.brussels\/nl\/overzicht\/","og_site_name":"CPAS d&#039;Ixelles","article_modified_time":"2025-12-17T15:05:35+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/cpasixelles.brussels\/wp-content\/uploads\/2022\/02\/MicrosoftTeams-image-8.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"3 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cpasixelles.brussels\/nl\/overzicht\/","url":"https:\/\/cpasixelles.brussels\/nl\/overzicht\/","name":"Overzicht - CPAS d&#039;Ixelles","isPartOf":{"@id":"https:\/\/cpasixelles.brussels\/#website"},"datePublished":"2025-12-17T14:41:01+00:00","dateModified":"2025-12-17T15:05:35+00:00","breadcrumb":{"@id":"https:\/\/cpasixelles.brussels\/nl\/overzicht\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpasixelles.brussels\/nl\/overzicht\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cpasixelles.brussels\/nl\/overzicht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cpasixelles.brussels\/nl\/"},{"@type":"ListItem","position":2,"name":"Overzicht"}]},{"@type":"WebSite","@id":"https:\/\/cpasixelles.brussels\/#website","url":"https:\/\/cpasixelles.brussels\/","name":"CPAS d&#039;Ixelles","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpasixelles.brussels\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/cpasixelles.brussels\/nl\/wp-json\/wp\/v2\/pages\/7879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpasixelles.brussels\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cpasixelles.brussels\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cpasixelles.brussels\/nl\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cpasixelles.brussels\/nl\/wp-json\/wp\/v2\/comments?post=7879"}],"version-history":[{"count":7,"href":"https:\/\/cpasixelles.brussels\/nl\/wp-json\/wp\/v2\/pages\/7879\/revisions"}],"predecessor-version":[{"id":8213,"href":"https:\/\/cpasixelles.brussels\/nl\/wp-json\/wp\/v2\/pages\/7879\/revisions\/8213"}],"up":[{"embeddable":true,"href":"https:\/\/cpasixelles.brussels\/nl\/wp-json\/wp\/v2\/pages\/6975"}],"wp:attachment":[{"href":"https:\/\/cpasixelles.brussels\/nl\/wp-json\/wp\/v2\/media?parent=7879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}